{"id":74866,"date":"2013-06-18T19:00:17","date_gmt":"2013-06-18T22:00:17","guid":{"rendered":"http:\/\/www.agrund.com\/?p=74866"},"modified":"2013-06-18T19:00:17","modified_gmt":"2013-06-18T22:00:17","slug":"financiamento-james-franco-pede-r-1-milhao-em-crowndfunding","status":"publish","type":"post","link":"https:\/\/agrund.com\/index.php\/financiamento-james-franco-pede-r-1-milhao-em-crowndfunding\/","title":{"rendered":"Financiamento :: James Franco pede R$ 1 milh\u00e3o em crowndfunding"},"content":{"rendered":"<p>O ator James Franco est\u00e1 recorrendo ao crowndfunding, tipo de financiamento pela internet, para levantar verba para a produ\u00e7\u00e3o de uma s\u00e9rie de filmes baseados em seu livro, &#8216;Palo Alto Stories&#8217;. Franco pede por mais de R$ 1 milh\u00e3o no site Indiegogo para ajudar no financiamento das produ\u00e7\u00f5es &#8216;Memoria&#8217;, &#8216;Killing Animals&#8217; e &#8216;Yosemite&#8217;.<\/p>\n<p>O ator listou jovens cineastas, incluindo Nina Ljeti, Vladimir Bourdeau, Bruce Thierry Cheung e Gabriel Demestree para dirigir partes dos filmes, mas n\u00e3o se sabe se ele mesmo assinar\u00e1 a dire\u00e7\u00e3o das produ\u00e7\u00f5es.<\/p>\n<p>&#8220;Mesmo sendo uma fic\u00e7\u00e3o, o livro \u00e9 inspirado em experi\u00eancias que tive crescendo aqui. Costumo encarar como uma obra que pode tocar em pontos universais sobre ser adolescente, e crescer, e aprender sobre um mundo maior&#8221;, disse em v\u00eddeo no site Indiegogo.<\/p>\n<p>Caso Franco alcance a meta de arrecada\u00e7\u00e3o e produza os filmes, todos os lucros ser\u00e3o revertidos para o &#8216;Art od Elysium&#8217;, institui\u00e7\u00e3o de caridade que beneficia crian\u00e7as com problemas m\u00e9dicos graves.<\/p>\n<p>Doadores que apoiarem o projeto via crowndfunding ganhar\u00e3o pr\u00eamios que v\u00e3o desde uma grava\u00e7\u00e3o de voz pessoal de Franco, para aqueles que doarem R$ 1 mil, ou uma pintura do astro, para quem desembolsar mais de R$ 15 mil.<\/p>\n<div id=\"attachment_74867\" style=\"width: 506px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/2013\/06\/financiamento-james-franco-pede-r-1-milhao-em-crowndfunding.jpeg\"><img aria-describedby=\"caption-attachment-74867\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-74867 \" alt=\"Financiamento :: James Franco pede R$ 1 milh\u00e3o em crowndfunding\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/2013\/06\/financiamento-james-franco-pede-r-1-milhao-em-crowndfunding.jpeg?resize=496%2C323\" width=\"496\" height=\"323\" data-recalc-dims=\"1\" \/><\/a><p id=\"caption-attachment-74867\" class=\"wp-caption-text\">Financiamento :: James Franco pede R$ 1 milh\u00e3o em crowndfunding<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Imagem: Reprodu\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ator James Franco est\u00e1 recorrendo ao crowndfunding, tipo de financiamento pela internet, para levantar verba para a produ\u00e7\u00e3o de uma s\u00e9rie de filmes baseados em seu livro, &#8216;Palo Alto Stories&#8217;. Franco pede por mais de R$ 1 milh\u00e3o no site Indiegogo para ajudar no financiamento das produ\u00e7\u00f5es &#8216;Memoria&#8217;, &#8216;Killing Animals&#8217; e &#8216;Yosemite&#8217;. O ator [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":74868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3Hz0n-jtw","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/74866"}],"collection":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/comments?post=74866"}],"version-history":[{"count":0,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/74866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media?parent=74866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/categories?post=74866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/tags?post=74866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}