{"id":74383,"date":"2013-06-13T10:00:15","date_gmt":"2013-06-13T13:00:15","guid":{"rendered":"http:\/\/www.agrund.com\/?p=74383"},"modified":"2013-06-13T10:00:15","modified_gmt":"2013-06-13T13:00:15","slug":"autobiografia-jackie-chan-esta-escrevendo-musical","status":"publish","type":"post","link":"https:\/\/agrund.com\/index.php\/autobiografia-jackie-chan-esta-escrevendo-musical\/","title":{"rendered":"Autobiografia :: Jackie Chan est\u00e1 escrevendo musical"},"content":{"rendered":"<p>Jackie Chan est\u00e1 escrevendo um musical baseado em sua vida. O lend\u00e1rio ator de artes marciais confirmou que est\u00e1 adaptando a sua autobiografia &#8216;I Am Jackie Chan: Minha Vida em A\u00e7\u00e3o&#8217;, lan\u00e7ada em 1998, para uma pe\u00e7a musical, que ele vai narrar. Falando a jornalistas numa coletiva de imprensa em Nova York na segunda-feira (11), ele disse: &#8220;Estamos \u00e0 procura de um diretor para a pe\u00e7a agora.&#8221;<\/p>\n<p>A estrela de 59 anos ir\u00e1 documentar sua vida desde seus primeiros anos em Hong Kong at\u00e9 o per\u00edodo do grupo juvenil de acrobacia Seven Little Fortunes, bem como sua batalha para se libertar da sombra da lenda das artes marciais Bruce Lee.<\/p>\n<p>Jackie j\u00e1 havia expressado seu amor por filmes musicais, particularmente pelo cl\u00e1ssico &#8216;A Novi\u00e7a Rebelde&#8217;, lan\u00e7ado em 1965 e estrelado por Julie Andrews e Christopher Plummer. Ele disse na \u00e9poca: &#8220;Eu amo &#8216;A Novi\u00e7a Rebelde&#8217;. Quando eu era crian\u00e7a, eu n\u00e3o sabia Ingl\u00eas e via o filme inteiro.&#8221;<\/p>\n<p>A estrela ic\u00f4nica est\u00e1 sendo homenageada por seu trabalho no cinema, tanto em Hollywood como em sua terra natal, Hong Kong. Na semana passada, o ator &#8211; assim como muitas estrelas antes dele &#8211; deixou os p\u00e9s e m\u00e3os gravados do lado de fora do famoso Chinese Theatre, em Hollywood. Jackie j\u00e1 havia participado da cerim\u00f4nia de prest\u00edgio em 1997, mas sua placa de cimento desapareceu misteriosamente. O astro tamb\u00e9m recebeu um pr\u00eamio no Festival de Cinema Asi\u00e1tico de Nova Iorque na segunda-feira (11).<\/p>\n<div id=\"attachment_74384\" style=\"width: 568px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/2013\/06\/autobiografia-jackie-chan-esta-escrevendo-musical.jpg\"><img aria-describedby=\"caption-attachment-74384\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-74384 \" alt=\"Autobiografia :: Jackie Chan est\u00e1 escrevendo musical\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/2013\/06\/autobiografia-jackie-chan-esta-escrevendo-musical.jpg?resize=558%2C315\" width=\"558\" height=\"315\" data-recalc-dims=\"1\" \/><\/a><p id=\"caption-attachment-74384\" class=\"wp-caption-text\">Autobiografia :: Jackie Chan est\u00e1 escrevendo musical<\/p><\/div>\n<p>Imagem: Reprodu\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jackie Chan est\u00e1 escrevendo um musical baseado em sua vida. O lend\u00e1rio ator de artes marciais confirmou que est\u00e1 adaptando a sua autobiografia &#8216;I Am Jackie Chan: Minha Vida em A\u00e7\u00e3o&#8217;, lan\u00e7ada em 1998, para uma pe\u00e7a musical, que ele vai narrar. Falando a jornalistas numa coletiva de imprensa em Nova York na segunda-feira (11), [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":74385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3Hz0n-jlJ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/74383"}],"collection":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/comments?post=74383"}],"version-history":[{"count":0,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/74383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media?parent=74383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/categories?post=74383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/tags?post=74383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}