{"id":163613,"date":"2017-03-03T15:00:53","date_gmt":"2017-03-03T18:00:53","guid":{"rendered":"http:\/\/www.agrund.com\/?p=163613"},"modified":"2017-03-03T14:25:51","modified_gmt":"2017-03-03T17:25:51","slug":"mules-as-queridinhas-da-estacao","status":"publish","type":"post","link":"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/","title":{"rendered":"Mules, as queridinhas da esta\u00e7\u00e3o!"},"content":{"rendered":"<p>Por <a href=\"http:\/\/blogdathay.com.br\/\">Thay Sanqueta<\/a><\/p>\n<p>Elas est\u00e3o por todos os lados. As mules parecem ser as queridinhas da esta\u00e7\u00e3o. Lisas, flats, com salto bloco, em tecidos estampados e at\u00e9 em veludo. Afinal elas s\u00e3o confort\u00e1veis e v\u00e3o bem com praticamente todos os looks, deixando a produ\u00e7\u00e3o mais elegante e fashionista.<\/p>\n<p>Aposte nelas!<\/p>\n<div id=\"attachment_163614\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163614\" data-attachment-id=\"163614\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/eva-chen-by-styledumonde-street-style-fashion-blog_mg_7575-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Eva-Chen-by-STYLEDUMONDE-Street-Style-Fashion-Blog_MG_7575-1-e1488561705636.jpg?fit=500%2C351&amp;ssl=1\" data-orig-size=\"500,351\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Acielle&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1394031238&quot;,&quot;copyright&quot;:&quot;STYLE DU MONDE&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.00025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Eva-Chen-by-STYLEDUMONDE-Street-Style-Fashion-Blog_MG_7575-1-e1488561705636.jpg?fit=300%2C211&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Eva-Chen-by-STYLEDUMONDE-Street-Style-Fashion-Blog_MG_7575-1-e1488561705636.jpg?fit=500%2C351&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163614\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Eva-Chen-by-STYLEDUMONDE-Street-Style-Fashion-Blog_MG_7575-1-e1488561705636.jpg?resize=500%2C351\" alt=\"\" width=\"500\" height=\"351\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163614\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163615\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163615\" data-attachment-id=\"163615\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/mule-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-2-e1488561718491.jpg?fit=500%2C313&amp;ssl=1\" data-orig-size=\"500,313\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-2-e1488561718491.jpg?fit=300%2C188&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-2-e1488561718491.jpg?fit=500%2C313&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163615\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-2-e1488561718491.jpg?resize=500%2C313\" alt=\"\" width=\"500\" height=\"313\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163615\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163616\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163616\" data-attachment-id=\"163616\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/mule-600x408\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/MULE-600x408-e1488561732878.jpg?fit=500%2C340&amp;ssl=1\" data-orig-size=\"500,340\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/MULE-600x408-e1488561732878.jpg?fit=300%2C204&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/MULE-600x408-e1488561732878.jpg?fit=500%2C340&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163616\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/MULE-600x408-e1488561732878.jpg?resize=500%2C340\" alt=\"\" width=\"500\" height=\"340\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163616\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163617\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163617\" data-attachment-id=\"163617\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/olympus-digital-camera\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-tende\u0302ncia-vera\u0303o-2015-calc\u0327ados-femininos6-e1488561813173.jpg?fit=500%2C375&amp;ssl=1\" data-orig-size=\"500,375\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;OLYMPUS DIGITAL CAMERA&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-tende\u0302ncia-vera\u0303o-2015-calc\u0327ados-femininos6-e1488561813173.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-tende\u0302ncia-vera\u0303o-2015-calc\u0327ados-femininos6-e1488561813173.jpg?fit=500%2C375&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163617\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule-tende\u0302ncia-vera\u0303o-2015-calc\u0327ados-femininos6-e1488561813173.jpg?resize=500%2C375\" alt=\"\" width=\"500\" height=\"375\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163617\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163618\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163618\" data-attachment-id=\"163618\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/mule1\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule1-e1488561827279.jpg?fit=500%2C266&amp;ssl=1\" data-orig-size=\"500,266\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule1-e1488561827279.jpg?fit=300%2C159&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule1-e1488561827279.jpg?fit=500%2C266&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163618\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/mule1-e1488561827279.jpg?resize=500%2C266\" alt=\"\" width=\"500\" height=\"266\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163618\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163619\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163619\" data-attachment-id=\"163619\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/sapato-mule-975344_w500h492\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?fit=500%2C492&amp;ssl=1\" data-orig-size=\"500,492\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?fit=300%2C295&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?fit=500%2C492&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163619\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?resize=500%2C492\" alt=\"\" width=\"500\" height=\"492\" srcset=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-975344_w500h492.jpg?resize=300%2C295&amp;ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163619\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163620\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163620\" data-attachment-id=\"163620\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/sapato-mule-esta-de-volta-mais-uma-vez\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Sapato-mule-esta\u0301-de-volta-mais-uma-vez-e1488561847227.jpg?fit=500%2C332&amp;ssl=1\" data-orig-size=\"500,332\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Sapato-mule-esta\u0301-de-volta-mais-uma-vez-e1488561847227.jpg?fit=300%2C199&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Sapato-mule-esta\u0301-de-volta-mais-uma-vez-e1488561847227.jpg?fit=500%2C332&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163620\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/Sapato-mule-esta\u0301-de-volta-mais-uma-vez-e1488561847227.jpg?resize=500%2C332\" alt=\"\" width=\"500\" height=\"332\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163620\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<div id=\"attachment_163621\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163621\" data-attachment-id=\"163621\" data-permalink=\"https:\/\/agrund.com\/index.php\/mules-as-queridinhas-da-estacao\/sapato-mule-verao-2013-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?fit=500%2C316&amp;ssl=1\" data-orig-size=\"500,316\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mules, as queridinhas da esta\u00e7\u00e3o!\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Mules, as queridinhas da esta\u00e7\u00e3o!&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?fit=300%2C190&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?fit=500%2C316&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163621\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?resize=500%2C316\" alt=\"\" width=\"500\" height=\"316\" srcset=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/sapato-mule-verao-2013-2.jpg?resize=300%2C190&amp;ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163621\" class=\"wp-caption-text\">Mules, as queridinhas da esta\u00e7\u00e3o!<\/p><\/div>\n<p>Fotos: Reprodu\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Thay Sanqueta Elas est\u00e3o por todos os lados. As mules parecem ser as queridinhas da esta\u00e7\u00e3o. Lisas, flats, com salto bloco, em tecidos estampados e at\u00e9 em veludo. Afinal elas s\u00e3o confort\u00e1veis e v\u00e3o bem com praticamente todos os looks, deixando a produ\u00e7\u00e3o mais elegante e fashionista. Aposte nelas! Fotos: Reprodu\u00e7\u00e3o.<\/p>\n","protected":false},"author":8,"featured_media":163622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/03\/s-14.jpg?fit=960%2C300&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3Hz0n-GyV","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/163613"}],"collection":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/comments?post=163613"}],"version-history":[{"count":0,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/163613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media\/163622"}],"wp:attachment":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media?parent=163613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/categories?post=163613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/tags?post=163613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}