{"id":163403,"date":"2017-02-24T17:00:18","date_gmt":"2017-02-24T20:00:18","guid":{"rendered":"http:\/\/www.agrund.com\/?p=163403"},"modified":"2017-02-24T10:21:06","modified_gmt":"2017-02-24T13:21:06","slug":"protestos-nas-passarelas","status":"publish","type":"post","link":"https:\/\/agrund.com\/index.php\/protestos-nas-passarelas\/","title":{"rendered":"Protestos nas passarelas"},"content":{"rendered":"<p>Por Let\u00edcia Santana<\/p>\n<p>N\u00e3o \u00e9 de hoje que eu falo que se vestir tamb\u00e9m pode ser um ato pol\u00edtico e as passarelas desta \u00faltima New York Fashion Week provam isso. Estilistas (muitos s\u00e3o, inclusive, imigrantes) aproveitaram os holofotes e os seus pesos na ind\u00fastria para protestar e mostrar que n\u00e3o est\u00e3o satisfeitos com muitas quest\u00f5es envolvendo direitos humanos e a atmosfera pol\u00edtica em geral que norteia a nossa sociedade.<\/p>\n<div id=\"attachment_163405\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163405\" data-attachment-id=\"163405\" data-permalink=\"https:\/\/agrund.com\/index.php\/protestos-nas-passarelas\/t-shirts-de-prabal-gurung\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/T-shirts-de-Prabal-Gurung-e1487942285185.jpeg?fit=600%2C435&amp;ssl=1\" data-orig-size=\"600,435\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Protestos nas passarelas\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Protestos nas passarelas&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/T-shirts-de-Prabal-Gurung-e1487942285185.jpeg?fit=300%2C217&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/T-shirts-de-Prabal-Gurung-e1487942285185.jpeg?fit=1024%2C742&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163405\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/T-shirts-de-Prabal-Gurung-e1487942285185.jpeg?resize=600%2C435\" alt=\"\" width=\"600\" height=\"435\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163405\" class=\"wp-caption-text\">Protestos nas passarelas<\/p><\/div>\n<p>Entre algumas manifesta\u00e7\u00f5es sutis e discretas, Prabal Gurung se manifestou de forma forte e impactante. Dezenas de modelos cruzaram a passarela vestindo camisetas com mensagens ativistas. O estilista contou que participou da Marcha das Mulheres &#8211; protestos que rolaram no \u00faltimo m\u00eas em diversas cidades dos Estados Unidos e do mundo &#8211; e foram os cartazes vistos por l\u00e1 que o inspiraram a fazer as t-shirts. Al\u00e9m disso, Gurung tamb\u00e9m trouxe modelos plus size para as passarelas.<\/p>\n<div id=\"attachment_163406\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163406\" data-attachment-id=\"163406\" data-permalink=\"https:\/\/agrund.com\/index.php\/protestos-nas-passarelas\/tied-together-por-tommy-hilfiger\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Tied-Together-por-Tommy-Hilfiger-e1487942308607.jpeg?fit=600%2C472&amp;ssl=1\" data-orig-size=\"600,472\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Protestos nas passarelas\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Protestos nas passarelas&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Tied-Together-por-Tommy-Hilfiger-e1487942308607.jpeg?fit=300%2C236&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Tied-Together-por-Tommy-Hilfiger-e1487942308607.jpeg?fit=1024%2C805&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163406\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Tied-Together-por-Tommy-Hilfiger-e1487942308607.jpeg?resize=600%2C472\" alt=\"\" width=\"600\" height=\"472\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163406\" class=\"wp-caption-text\">Protestos nas passarelas<\/p><\/div>\n<p>Tommy Hilfiger apresentou sua nova cole\u00e7\u00e3o em parceria com Gigi Hadid em um desfile em Los Angeles repleto de insta-top-models. Todo o casting entrou na passarela usando uma bandana branca amarrada no pulso do bra\u00e7o esquerdo em prol da uni\u00e3o. A\u00e7\u00e3o essa que se chama \u201cTied Together\u201d e foi criada pelo importante site Business of Fashion em solidariedade aos imigrantes e minorias. O intuito \u00e9 o seguinte: \u201cum movimento silencioso e n\u00e3o necessariamente uma declara\u00e7\u00e3o pol\u00edtica, mas, sim, de positividade em apoio \u00e0 humanidade, incentivando entusiastas da moda e pessoas de fora da ind\u00fastria a participar\u201d.<\/p>\n<div id=\"attachment_163404\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-163404\" data-attachment-id=\"163404\" data-permalink=\"https:\/\/agrund.com\/index.php\/protestos-nas-passarelas\/palavras-de-the-row\/\" data-orig-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Palavras-de-The-Row-e1487942324279.jpeg?fit=600%2C395&amp;ssl=1\" data-orig-size=\"600,395\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Protestos nas passarelas\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Protestos nas passarelas&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Palavras-de-The-Row-e1487942324279.jpeg?fit=300%2C198&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Palavras-de-The-Row-e1487942324279.jpeg?fit=1024%2C675&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-163404\" src=\"https:\/\/i0.wp.com\/www.agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/Palavras-de-The-Row-e1487942324279.jpeg?resize=600%2C395\" alt=\"\" width=\"600\" height=\"395\" data-recalc-dims=\"1\" \/><p id=\"caption-attachment-163404\" class=\"wp-caption-text\">Protestos nas passarelas<\/p><\/div>\n<p>N\u00e3o \u00e9 de hoje que as g\u00eameas Ashley e Mary Kate Olsen, donas da marca The Row, s\u00e3o engajadas socialmente. O desfile super aplaudido pela alta cr\u00edtica da moda devido \u00e0s suas roupas muito bem desenhadas tamb\u00e9m deu voz ao movimento. A manifesta\u00e7\u00e3o sutil, por\u00e9m n\u00e3o menos importante, aconteceu no bordado das camisas brancas: palavras como \u201cliberdade\u201d, \u201cdignidade\u201d e \u201cesperan\u00e7a\u201d foram costuradas.<\/p>\n<p>Moda tamb\u00e9m pode ser voz contra a intoler\u00e2ncia.<\/p>\n<p>Mais em\u00a0<a href=\"http:\/\/borboletavintage.com.br\/\">Borboleta Vintage<\/a>.<br \/>\nInstagram: <a href=\"https:\/\/www.instagram.com\/borboletavintage\/\">@borboletavintage<\/a>.<\/p>\n<p>Fotos: Reprodu\u00e7\u00e3o\/Borboleta Vintage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Let\u00edcia Santana N\u00e3o \u00e9 de hoje que eu falo que se vestir tamb\u00e9m pode ser um ato pol\u00edtico e as passarelas desta \u00faltima New York Fashion Week provam isso. Estilistas (muitos s\u00e3o, inclusive, imigrantes) aproveitaram os holofotes e os seus pesos na ind\u00fastria para protestar e mostrar que n\u00e3o est\u00e3o satisfeitos com muitas quest\u00f5es [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":163407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/agrund.com\/wp-content\/uploads\/sites\/6\/2017\/02\/s-118.jpg?fit=960%2C300&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3Hz0n-Gvx","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/163403"}],"collection":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/comments?post=163403"}],"version-history":[{"count":0,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/posts\/163403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media\/163407"}],"wp:attachment":[{"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/media?parent=163403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/categories?post=163403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrund.com\/index.php\/wp-json\/wp\/v2\/tags?post=163403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}